{"id":7674,"date":"2026-07-15T10:43:11","date_gmt":"2026-07-15T10:43:11","guid":{"rendered":"https:\/\/rightnow.mx\/index.php\/2026\/07\/15\/influencer-que-denuncio-violencia-de-su-ex-muere-y-deja-mas-preguntas-que-respuestas\/"},"modified":"2026-07-15T16:43:22","modified_gmt":"2026-07-15T16:43:22","slug":"influencer-que-denuncio-violencia-de-su-ex-muere-y-deja-mas-preguntas-que-respuestas","status":"publish","type":"post","link":"https:\/\/rightnow.mx\/index.php\/2026\/07\/15\/influencer-que-denuncio-violencia-de-su-ex-muere-y-deja-mas-preguntas-que-respuestas\/","title":{"rendered":"Influencer que denunci\u00f3 violencia de su ex muere y deja m\u00e1s preguntas que respuestas"},"content":{"rendered":"<p>Marie Claire Gonz\u00e1lez, influencer, empresaria y fundadora de Executive Lab, falleci\u00f3 recientemente tras haber hecho p\u00fablicas semanas atr\u00e1s las agresiones f\u00edsicas y psicol\u00f3gicas que sufri\u00f3 por parte de su expareja.  <\/p>\n<p>A sus 39 a\u00f1os, Gonz\u00e1lez no solo era una voz activa contra la violencia de g\u00e9nero, sino tambi\u00e9n una promotora del emprendimiento femenino y el bienestar emocional. En sus redes sociales, compart\u00eda mensajes claros para quienes enfrentan maltrato: \u201cAprende a reconocer las se\u00f1ales del abuso y del maltrato psicol\u00f3gico. Habla. Busca ayuda\u201d, escribi\u00f3 mientras mostraba un moret\u00f3n en el rostro, evidencia de su lucha.  <\/p>\n<p>\u201cSi te sientes identificad@ con lo aqu\u00ed escribo, te recomiendo refugiarte en tus seres queridos y decirles c\u00f3mo te sientes. Te dejo textos para que leas m\u00e1s al respecto, porque NO est\u00e1s loca como te lo han hecho creer, NI EST\u00c1S EXAGERANDO\u201d, insist\u00eda en sus publicaciones.  <\/p>\n<p>Aunque la muerte de Marie Claire fue confirmada hace poco, las causas a\u00fan no se han esclarecido. Medios internacionales, incluyendo algunos de Panam\u00e1, apuntan a una posible l\u00ednea de investigaci\u00f3n sobre suicidio, pero esta versi\u00f3n no ha sido confirmada oficialmente.  <\/p>\n<p>Mientras las autoridades contin\u00faan con las indagatorias, familiares, amigos y seguidores han expresado su dolor y condolencias por la p\u00e9rdida de una figura que, m\u00e1s all\u00e1 de su influencia digital, representaba un ejemplo de resiliencia y liderazgo en Centroam\u00e9rica.  <\/p>\n<p>Marie Claire Gonz\u00e1lez no solo fue influencer; fue empresaria, escritora, conferencista y excongresista paname\u00f1a, reconocida por Forbes como una de las mujeres m\u00e1s influyentes de la regi\u00f3n. Su legado en el impulso del liderazgo femenino y la innovaci\u00f3n empresarial sigue vigente, record\u00e1ndonos que detr\u00e1s de cada historia p\u00fablica hay una persona con luchas profundas.  <\/p>\n<p>En un mundo donde la violencia contra la mujer sigue siendo un tema urgente, su historia invita a reflexionar sobre la importancia de proteger la integridad y la vida de quienes alzan la voz, sin que el Estado intervenga de forma excesiva, sino garantizando el orden y la justicia efectiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marie Claire Gonz\u00e1lez, influencer, empresaria y fundadora de Executive Lab, falleci\u00f3 recientemente tras haber hecho p\u00fablicas semanas atr\u00e1s las agresiones f\u00edsicas y psicol\u00f3gicas que sufri\u00f3 por parte de su expareja. A sus 39 a\u00f1os, Gonz\u00e1lez no solo era una voz activa contra la violencia de g\u00e9nero, sino tambi\u00e9n una promotora del emprendimiento femenino y el&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/rightnow.mx\/index.php\/2026\/07\/15\/influencer-que-denuncio-violencia-de-su-ex-muere-y-deja-mas-preguntas-que-respuestas\/\" class=\"excerpt-read-more\">Ver M\u00e1s<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":7673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/posts\/7674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7674"}],"version-history":[{"count":1,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/posts\/7674\/revisions"}],"predecessor-version":[{"id":7675,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/posts\/7674\/revisions\/7675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/media\/7673"}],"wp:attachment":[{"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rightnow.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}